{"id":12259,"date":"2025-06-26T08:42:17","date_gmt":"2025-06-26T08:42:17","guid":{"rendered":"https:\/\/www.hndfcrane.com\/?p=12259"},"modified":"2025-06-26T08:42:20","modified_gmt":"2025-06-26T08:42:20","slug":"overhead-crane-solutions-for-railways","status":"publish","type":"post","link":"https:\/\/www.hndfcrane.com\/it\/overhead-crane-solutions-for-railways\/","title":{"rendered":"Soluzioni per gru a ponte per ferrovie: posa binari, manutenzione del materiale rotabile e movimentazione container"},"content":{"rendered":"<div class=\"pgc-sgb-cb wp-block-pgcsimplygalleryblock-grid  hndfgallery\" data-gallery-id=\"23c38974\"><div class=\"sgb-preloader\" id=\"pr_23c38974\">\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div><\/div><div class=\"simply-gallery-amp pgc_sgb_slider\" style=\"display: none;\"><div class=\"sgb-gallery\"><div class=\"sgb-item\"><a href=\"https:\/\/www.hndfcrane.com\/it\/overhead-crane-solutions-for-railways\/rmg-rail-mounted-container-gantry-crane\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"900\" height=\"601\" loading=\"lazy\" src=\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/RMG-rail-mounted-container-gantry-crane.png\" srcset=\",https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/RMG-rail-mounted-container-gantry-crane.png 900w\" sizes=\"250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.hndfcrane.com\/it\/overhead-crane-solutions-for-railways\/single-girder-overhead-crane-6\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"1280\" height=\"853\" loading=\"lazy\" src=\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/Single-Girder-Overhead-Crane.jpg\" srcset=\",https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/Single-Girder-Overhead-Crane.jpg 1280w\" sizes=\"250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.hndfcrane.com\/it\/overhead-crane-solutions-for-railways\/double-girder-overhead-crane-4\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"905\" height=\"600\" loading=\"lazy\" src=\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/Double-Girder-Overhead-Crane.png\" srcset=\",https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/Double-Girder-Overhead-Crane.png 905w\" sizes=\"250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.hndfcrane.com\/it\/overhead-crane-solutions-for-railways\/double-girder-gantry-crane-7\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"900\" height=\"601\" loading=\"lazy\" src=\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/double-girder-gantry-crane.png\" srcset=\",https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/double-girder-gantry-crane.png 900w\" sizes=\"250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.hndfcrane.com\/it\/overhead-crane-solutions-for-railways\/track-laying-machine\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"900\" height=\"600\" loading=\"lazy\" src=\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/track-laying-machine.png\" srcset=\",https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/track-laying-machine.png 900w\" sizes=\"250px\"\/><\/a><\/div><\/div><\/div><script type=\"application\/json\" class=\"sgb-data\">{\"galleryType\":\"pgc_sgb_grid\",\"galleryId\":\"23c38974\",\"images\":[{\"id\":12270,\"title\":\"RMG-rail-mounted-container-gantry-crane\",\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/RMG-rail-mounted-container-gantry-crane.png\",\"link\":\"https:\/\/www.hndfcrane.com\/?attachment_id=12270\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/png\",\"type\":\"image\",\"width\":900,\"height\":601,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/RMG-rail-mounted-container-gantry-crane-150x150.png\",\"height\":150,\"width\":150,\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/RMG-rail-mounted-container-gantry-crane.png\",\"height\":601,\"width\":900,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.hndfcrane.com\/?attachment_id=12270\"},{\"id\":12276,\"title\":\"Single-Girder-Overhead-Crane\",\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/Single-Girder-Overhead-Crane.jpg\",\"link\":\"https:\/\/www.hndfcrane.com\/?attachment_id=12276\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":853,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/Single-Girder-Overhead-Crane-150x150.jpg\",\"height\":150,\"width\":150,\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/Single-Girder-Overhead-Crane.jpg\",\"height\":853,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.hndfcrane.com\/?attachment_id=12276\"},{\"id\":12275,\"title\":\"Double-Girder-Overhead-Crane\",\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/Double-Girder-Overhead-Crane.png\",\"link\":\"https:\/\/www.hndfcrane.com\/?attachment_id=12275\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/png\",\"type\":\"image\",\"width\":905,\"height\":600,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/Double-Girder-Overhead-Crane-150x150.png\",\"height\":150,\"width\":150,\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/Double-Girder-Overhead-Crane.png\",\"height\":600,\"width\":905,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.hndfcrane.com\/?attachment_id=12275\"},{\"id\":12274,\"title\":\"double-girder-gantry-crane\",\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/double-girder-gantry-crane.png\",\"link\":\"https:\/\/www.hndfcrane.com\/?attachment_id=12274\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/png\",\"type\":\"image\",\"width\":900,\"height\":601,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/double-girder-gantry-crane-150x150.png\",\"height\":150,\"width\":150,\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/double-girder-gantry-crane.png\",\"height\":601,\"width\":900,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.hndfcrane.com\/?attachment_id=12274\"},{\"id\":12277,\"title\":\"track-laying-machine\",\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/track-laying-machine.png\",\"link\":\"https:\/\/www.hndfcrane.com\/?attachment_id=12277\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/png\",\"type\":\"image\",\"width\":900,\"height\":600,\"sizes\":{\"thumbnail\":{\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/track-laying-machine-150x150.png\",\"height\":150,\"width\":150,\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/track-laying-machine.png\",\"height\":600,\"width\":900,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"0\",\"credit\":\"\",\"camera\":\"\",\"caption\":\"\",\"created_timestamp\":\"0\",\"copyright\":\"\",\"focal_length\":\"0\",\"iso\":\"0\",\"shutter_speed\":\"0\",\"title\":\"\",\"orientation\":\"0\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.hndfcrane.com\/?attachment_id=12277\"}],\"className\":\"hndfgallery\",\"itemsMetaDataCollection\":[]}<\/script><script>(function(){if(window.PGC_SGB && window.PGC_SGB.searcher){window.PGC_SGB.searcher.initBlocks()}})()<\/script><\/div>\n\n\n<h2 class=\"wp-block-heading\">Costruzione di infrastrutture ferroviarie<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Gru a portale per la posa dei binari della metropolitana<\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/track-laying-machine.png\" alt=\"\" class=\"wp-image-12277\"\/><\/figure>\n\n\n\n<p>La gru a portale per la posa dei binari della metropolitana adotta paranchi elettrici di tipo CD1\/MD1, caratterizzati da una struttura semplice, prestazioni stabili e una lunga durata, per operazioni di sollevamento coordinate. Il meccanismo di traslazione della gru adotta dispositivi di azionamento verticali per azionamenti separati e il controllo pu\u00f2 essere effettuato tramite un collegamento singolo o multiplo. La gru a portale utilizza una struttura compatta di tipo scatolare, con campata e altezza variabili per adattarsi allo spazio della galleria. Durante il funzionamento, pi\u00f9 gru lavorano insieme per un sollevamento sincronizzato.<\/p>\n\n\n\n<ul>\n<li>Facile da installare e utilizzare, con bassi costi di manutenzione.<\/li>\n\n\n\n<li>Velocit\u00e0 di marcia regolabile ed elevata efficienza di manovrabilit\u00e0.<\/li>\n\n\n\n<li>Struttura compatta, adatta al funzionamento in spazi ristretti.<\/li>\n\n\n\n<li>Grande versatilit\u00e0, adatto a vari tipi di gallerie della metropolitana.<\/li>\n\n\n\n<li>Dotato di funzione di regolazione automatica dell&#39;altezza e della portata.<\/li>\n\n\n\n<li>Pu\u00f2 essere trasportato e ricollocato nella sua interezza.<\/li>\n\n\n\n<li>Questo tipo di gru a portale \u00e8 progettato specificamente per i progetti di posa dei binari della metropolitana. Viene utilizzato principalmente per il sollevamento di pannelli, casseforme e installazione di barre d&#39;armatura nella costruzione dei binari della metropolitana; il cantiere si svolge solitamente in spazi ristretti come le tratte della metropolitana.<\/li>\n\n\n\n<li>In base al carico e alla frequenza di utilizzo, la gru \u00e8 progettata con una classe di lavoro A3 o superiore.<\/li>\n\n\n\n<li>In base alle esigenze della costruzione della metropolitana, la gru a portale per la posa dei binari deve essere dotata di funzioni di regolazione automatica della campata e dell&#39;altezza; soddisfa le condizioni di lavoro di tutti i tipi di progetti di ingegneria ferroviaria per gallerie metropolitane in Cina. La gru pu\u00f2 attraversare banchine, porte a soffietto, piccole curve e cunicoli trasversali, e pu\u00f2 essere trasportata e riposizionata all&#39;interno delle gallerie senza essere smontata.<\/li>\n\n\n\n<li>Umidit\u00e0 relativa: 55\u00b0C\u201385\u00b0C; concentrazione di gas infiammabile non superiore a 10\u00b0C del limite inferiore di esplosivit\u00e0. Temperatura ambiente: -25\u00b0C~+40\u00b0C.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Produzione e manutenzione del materiale rotabile<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/Single-Girder-Overhead-Crane.jpg\" alt=\"\" class=\"wp-image-12276\"\/><figcaption class=\"wp-element-caption\">Gru a ponte monotrave<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"905\" height=\"600\" src=\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/Double-Girder-Overhead-Crane.png\" alt=\"\" class=\"wp-image-12275\"\/><figcaption class=\"wp-element-caption\">Gru a ponte a doppia trave<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"601\" src=\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/double-girder-gantry-crane.png\" alt=\"\" class=\"wp-image-12274\"\/><figcaption class=\"wp-element-caption\">Gru a cavalletto a doppia trave<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Gru a ponte monotrave<\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/Single-Girder-Overhead-Crane.jpg\" alt=\"\" class=\"wp-image-12276\"\/><\/figure>\n\n\n\n<p>Questo <a href=\"https:\/\/www.hndfcrane.com\/it\/single-girder-overhead-cranes\/\">carroponte monotrave<\/a> \u00e8 utilizzato principalmente per la produzione, l&#39;ispezione, la manutenzione e l&#39;assistenza di treni ad alta velocit\u00e0, metropolitane e tram.<\/p>\n\n\n\n<ul>\n<li>La gru completa adotta il design europeo, caratterizzato da peso proprio ridotto, bassa pressione sulle ruote e dimensioni compatte;<\/li>\n\n\n\n<li>Facile da usare, funzionamento regolare e basso rumore;<\/li>\n\n\n\n<li>Elevata precisione di posizionamento, sicuro e affidabile;<\/li>\n\n\n\n<li>Movimentazione precisa e affidabile del carico.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Gru a ponte a doppia trave<\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"905\" height=\"600\" src=\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/Double-Girder-Overhead-Crane.png\" alt=\"\" class=\"wp-image-12275\"\/><\/figure>\n\n\n\n<p>Questo <a href=\"https:\/\/www.hndfcrane.com\/it\/double-girder-overhead-cranes\/\">carroponte bitrave<\/a> viene utilizzato per sollevare veicoli su rotaia quali treni, treni ad alta velocit\u00e0, carrozze della metropolitana e vagoni merci, svolgendo compiti di ispezione e manutenzione nei depositi di servizio.<\/p>\n\n\n\n<ul>\n<li>Controllo della frequenza completamente variabile per un sollevamento e uno spostamento fluidi con il minimo impatto;<\/li>\n\n\n\n<li>Dotato di tecnologia anti-oscillazione per ridurre efficacemente l&#39;oscillazione del carico;<\/li>\n\n\n\n<li>I componenti strutturali vengono lavorati nel loro insieme per garantire la precisione dell&#39;installazione;<\/li>\n\n\n\n<li>Aspetto accattivante, design leggero e bassa rumorosit\u00e0.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Gru a cavalletto a doppia trave<\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"601\" src=\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/double-girder-gantry-crane.png\" alt=\"\" class=\"wp-image-12274\"\/><\/figure>\n\n\n\n<p>Questa gru a portale a doppia trave \u00e8 responsabile delle operazioni di produzione e sollevamento nei progetti ferroviari.<\/p>\n\n\n\n<ul>\n<li>Design leggero<\/li>\n\n\n\n<li>Bassa pressione delle ruote<\/li>\n\n\n\n<li>Senza manutenzione<\/li>\n\n\n\n<li>Funzionamento regolare<\/li>\n\n\n\n<li>Basso rumore<\/li>\n\n\n\n<li>Risparmio energetico e rispettoso dell&#39;ambiente<\/li>\n<\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Movimentazione container per ferrovia<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Gru a portale per container montata su rotaia RMG<\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"601\" src=\"https:\/\/www.hndfcrane.com\/wp-content\/uploads\/2025\/06\/RMG-rail-mounted-container-gantry-crane-for-railway.png\" alt=\"\" class=\"wp-image-12291\"\/><\/figure>\n\n\n\n<p>IL <a href=\"https:\/\/www.hndfcrane.com\/it\/rail-mounted-container-gantry-cranes\/\">gru a portale per container montata su rotaia<\/a> \u00c8 supportato da cingoli con pi\u00f9 set di ruote in acciaio ed \u00e8 alimentato dalla rete elettrica. \u00c8 costituito dal meccanismo di traslazione della gru, dal gruppo carrello, dal telaio del portale, dal sistema di alimentazione e dallo spreader specifico per container.<\/p>\n\n\n\n<p>Dafang Crane \u00e8 specializzata nella fornitura di:<\/p>\n\n\n\n<ul>\n<li>Gru a portale per container montate su rotaia a rotazione superiore (rotazione su carrello)<\/li>\n\n\n\n<li>Gru a portale per container montate su rotaia a rotazione inferiore (con rotazione dello spreader)<\/li>\n\n\n\n<li>Gru a portale per container montate su rotaia, a sbalzo e non a sbalzo<\/li>\n\n\n\n<li>Gru a portale per container montate su rotaia progettate specificamente per applicazioni ferroviarie<\/li>\n<\/ul>\n\n\n\n<p>I nostri prodotti sono compatibili con vari tipi e modelli di spanditori per container generici o specializzati, garantendo una movimentazione efficiente di container standard o speciali in diverse condizioni di lavoro.<\/p>","protected":false},"excerpt":{"rendered":"Gru a portale per la posa dei binari della metropolitana e la costruzione di infrastrutture ferroviarie. La gru a portale per la posa dei binari della metropolitana adotta paranchi elettrici di tipo CD1\/MD1, caratterizzati da una struttura semplice, prestazioni stabili e una lunga durata, per operazioni di sollevamento coordinate. Il meccanismo di traslazione della gru adotta dispositivi di azionamento verticali per azionamenti separati e il controllo pu\u00f2 essere realizzato tramite controllo a collegamento singolo o multiplo. Il [\u2026]","protected":false},"author":4,"featured_media":12275,"parent":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"single-new-Product.php","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hndfcrane.com\/it\/wp-json\/wp\/v2\/posts\/12259"}],"collection":[{"href":"https:\/\/www.hndfcrane.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hndfcrane.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hndfcrane.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hndfcrane.com\/it\/wp-json\/wp\/v2\/comments?post=12259"}],"version-history":[{"count":20,"href":"https:\/\/www.hndfcrane.com\/it\/wp-json\/wp\/v2\/posts\/12259\/revisions"}],"predecessor-version":[{"id":12310,"href":"https:\/\/www.hndfcrane.com\/it\/wp-json\/wp\/v2\/posts\/12259\/revisions\/12310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hndfcrane.com\/it\/wp-json\/wp\/v2\/media\/12275"}],"wp:attachment":[{"href":"https:\/\/www.hndfcrane.com\/it\/wp-json\/wp\/v2\/media?parent=12259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hndfcrane.com\/it\/wp-json\/wp\/v2\/categories?post=12259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hndfcrane.com\/it\/wp-json\/wp\/v2\/tags?post=12259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}